{"id":2645,"date":"2022-09-22T13:41:24","date_gmt":"2022-09-22T17:41:24","guid":{"rendered":"https://www.dawsoncollege.qc.ca/research/?p=2645"},"modified":"2022-09-22T13:41:24","modified_gmt":"2022-09-22T17:41:24","slug":"official-launch-of-nsercs-strategic-plan","status":"publish","type":"post","link":"https://www.dawsoncollege.qc.ca/research/official-launch-of-nsercs-strategic-plan/","title":{"rendered":"Official launch of NSERC’s strategic plan"},"content":{"rendered":"<p class=\"x_MsoNormal\"><span style=\"font-size: small\">Après des mois de collecte d'informations et de consultations auprès d'un large éventail de parties prenantes, nous avons le plaisir de partager avec vous notre nouveau plan stratégique, <a title=\"URL original : https://www.nserc-crsng.gc.ca/NSERC-CRSNG/NSERC2030-CRSNG2030/report-rapport/index_eng.asp. Cliquez ou tapez si vous faites confiance à ce lien.\" href=\"https://can01.safelinks.protection.outlook.com/?url=https%3A%2F%2Fwww.nserc-crsng.gc.ca%2FNSERC-CRSNG%2FNSERC2030-CRSNG2030%2Freport-rapport%2Findex_eng.asp&amp;data=05%7C01%7Ciglaserhille%40dawsoncollege.qc.ca%7C433ecc85dd4f41a72e9508da9cb84a66%7Cb6b66a7afbbb42b8a7c5712342094eef%7C1%7C0%7C637994613012658807%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C2000%7C%7C%7C&amp;sdata=Yudeipl0TTYtelxyeoJmI47OYReXehKIEE%2Br6rwSbcM%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"Verified\" data-linkindex=\"0\">CRSNG 2030 : Découverte, innovation, inclusion</a><span class=\"x_m_6217480310862669684MsoHyperlink\">. </span>Ce plan présente une vision ambitieuse de l'excellence de la recherche canadienne et du potentiel des sciences naturelles et du génie pour le bien-être de l'humanité et de notre planète.</span></p>\n<p class=\"x_MsoNormal\"><span style=\"font-size: small\"><span class=\"x_m_6217480310862669684MsoHyperlink\"><i>CRSNG 2030</i></span> s'articule <span class=\"x_m_6217480310862669684MsoHyperlink\"> autour de cinq piliers : appuyer l'</span>excellence en recherche qui renforce le Canada ; élargir, diversifier et soutenir le bassin de talents du Canada ; transformer les découvertes en retombées, mobiliser les connaissances à l'échelle mondiale et renforcer l'autonomie de notre organisme et de nos employés. Il souligne l'importance primordiale de l'équité, de la diversité, de l'accessibilité et de l'inclusion dans tous nos programmes et dans l'ensemble de l'écosystème de la recherche. Il s'engage également à développer un engagement plus profond et plus significatif avec les communautés, les organisations, les chercheurs et les stagiaires autochtones et à explorer le rôle de la science et de la recherche dans le cheminement vers la réconciliation.</span></p>\n<p>&nbsp;</p>\n<p>Pour lire le plan stratégique, veuillez cliquer <a href=\"https://www.nserc-crsng.gc.ca/NSERC-CRSNG/NSERC2030-CRSNG2030/report-rapport/index_eng.asp\" target=\"_blank\" rel=\"noopener\">ici</a></p>\n","protected":false},"excerpt":{"rendered":"<p>Après des mois de collecte d'informations et de consultations auprès d'un large éventail de parties prenantes, nous avons le plaisir de partager avec vous notre nouveau plan stratégique, CRSNG 2030 : Découverte, innovation, inclusion. Ce plan présente une vision ambitieuse de l'excellence de la recherche canadienne et du potentiel des sciences naturelles et du génie pour le bien-être de l'humanité et de nos...</p>\n","protected":false},"author":0,"featured_media":1803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,119,184,115,1],"tags":[175,194,135,178],"class_list":["post-2645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement","category-funding-agency-news","category-research","category-research-news","category-uncategorized","tag-canada","tag-nserc","tag-research","tag-strategic-plan"],"_links":{"self":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/types/post"}],"replies":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/comments?post=2645"}],"version-history":[{"count":1,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2645/revisions"}],"predecessor-version":[{"id":2646,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2645/revisions/2646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media/1803"}],"wp:attachment":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media?parent=2645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/categories?post=2645"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/tags?post=2645"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}