{"id":2123,"date":"2022-02-22T10:22:48","date_gmt":"2022-02-22T15:22:48","guid":{"rendered":"https://www.dawsoncollege.qc.ca/research/?p=2123"},"modified":"2022-02-22T10:22:48","modified_gmt":"2022-02-22T15:22:48","slug":"article-its-time-to-end-canadas-obsession-with-research-quantity","status":"publish","type":"post","link":"https://www.dawsoncollege.qc.ca/research/article-its-time-to-end-canadas-obsession-with-research-quantity/","title":{"rendered":"Article: It’s time to end Canada’s obsession with research quantity"},"content":{"rendered":"<p class=\"deck\">Un appel à mettre fin à la folie collective et préjudiciable selon laquelle nous publions peut-être plus, mais prenons encore plus de retard.</p>\n<div class=\"meta\">PAR ALEXANDER CLARK &amp;AMP; BAILEY SOUSA | FEB 14 2022</div>\n<div></div>\n<div>\n<p>Le bailleur de fonds national australien pour la recherche en matière de santé a décidé de limiter l'évaluation de chaque candidat à ses concours de recherche de marque à seulement <a href=\"https://www.nhmrc.gov.au/about-us/news-centre/changes-publication-assessment\">10 publications de la dernière décennie</a>.</p>\n<p>Tout au plus, 10. Laissez-vous convaincre.</p>\n<p>Il n'est pas nécessaire de maintenir ou de soumettre un CV commun détaillant chaque parcelle de chaque publication, engagement ou exposé auquel vous avez participé, ne serait-ce que de manière indirecte. Pas d'impact sur les revues ni de H-index. Seulement 10 publications sur 10 ans.</p>\n<p><strong> </strong>Qu'est-ce qui a conduit le Conseil national de la santé et de la recherche médicale (NHMRC) à prendre cette initiative audacieuse ? Le conseil <a href=\"https://www.nhmrc.gov.au/node/7855\">a précisé</a> qu'il s'agissait de valoriser la qualité de la recherche plutôt que la quantité. Il s'agit d'encourager la recherche rigoureuse, transparente et reproductible. La contribution est cruciale : les <a href=\"https://www.nhmrc.gov.au/node/7855\">candidats doivent non seulement expliquer</a> comment chaque publication a contribué à la connaissance et à la qualité, mais aussi faire part de l'impact de la publication et de ses contributions à leur leadership.</p>\n<p>Ce mouvement que vous sentez maintenant comme les poids lourds de la communauté de la recherche au Canada se déplaçant mal à l'aise dans leurs chaires (dotées). Sur quoi appuyer votre crédibilité externe et votre confiance interne si ce n'est sur vos 220 publications ? Il peut également s'agir de l'indignation des départements et des institutions qui, pendant des années, ont fondé leurs structures de récompense, leurs célébrations et leurs identités sur la réalisation de nombreuses recherches.</p>\n<p>Pourtant, ce changement n'est pas un signe d'apocalypse - c'est un changement dont le monde a besoin de toute urgence.</p>\n<p>Pour en savoir plus, <a href=\"https://www.universityaffairs.ca/career-advice/effective-successfull-happy-academic/its-time-to-end-canadas-obsession-with-research-quantity/?utm_source=University+Affairs+e-newsletter&amp;utm_campaign=276a847f70-EMAIL_CAMPAIGN_2022_02_16&amp;utm_medium=email&amp;utm_term=0_314bc2ee29-276a847f70-426974276\" target=\"_blank\" rel=\"noopener noreferrer\">cliquez ici</a></p>\n</div>\n","protected":false},"excerpt":{"rendered":"<p>Un appel pour mettre fin à la folie collective et préjudiciable qui veut que nous publiions plus, mais que nous prenions plus de retard. PAR ALEXANDER CLARK &amp; BAILEY SOUSA | FÉV 14 2022 Le bailleur de fonds national australien pour la recherche en santé a pris des mesures pour limiter l&#039;évaluation de chaque candidat à ses concours de recherche de marque à seulement 10 publications de la dernière décennie....</p>\n","protected":false},"author":0,"featured_media":1939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,167,166,127,115,1],"tags":[171,173,172,134,168,135,170,169],"class_list":["post-2123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement","category-article","category-commentary","category-higher-education-news","category-research-news","category-uncategorized","tag-article","tag-comment","tag-opinion","tag-professional-burnout","tag-publishing","tag-research","tag-research-dissemination","tag-research-production"],"_links":{"self":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/types/post"}],"replies":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/comments?post=2123"}],"version-history":[{"count":1,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2123/revisions"}],"predecessor-version":[{"id":2124,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2123/revisions/2124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media/1939"}],"wp:attachment":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media?parent=2123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/categories?post=2123"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/tags?post=2123"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}