{"id":2018,"date":"2021-11-19T10:42:36","date_gmt":"2021-11-19T15:42:36","guid":{"rendered":"https://www.dawsoncollege.qc.ca/research/?p=2018"},"modified":"2021-11-19T10:42:36","modified_gmt":"2021-11-19T15:42:36","slug":"government-launches-call-for-applications-for-projects-to-address-radicalization-to-violence","status":"publish","type":"post","link":"https://www.dawsoncollege.qc.ca/research/government-launches-call-for-applications-for-projects-to-address-radicalization-to-violence/","title":{"rendered":"Government launches Call for Applications for projects to address radicalization to violence"},"content":{"rendered":"<p>Le gouvernement du Canada s'est engagé à lutter contre la radicalisation vers la violence et à soutenir les initiatives visant à assurer la sécurité des Canadiens.</p>\n<p>Le 16 novembre, le ministre de la Sécurité publique, l'honorable Marco Mendicino, a invité les organisations intéressées à présenter une demande de financement dans le cadre du Fonds de résilience communautaire (FRC). À partir de 2022-23, un financement d'environ 6,5 millions de dollars sera disponible dans le cadre du FRC. Le FRC fournit des fonds aux organisations pour soutenir leurs programmes novateurs et leurs initiatives de recherche visant à lutter contre la radicalisation à la violence au Canada.</p>\n<p>Pour en savoir plus, cliquez <a href=\"https://educationnewscanada.com/article/education/category/0/0/930966/b-government-launches-call-for-applications-for-projects-to-address-radicalization-to-violence.html\" target=\"_blank\" rel=\"noopener noreferrer\">ici</a></p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement du Canada s'est engagé à lutter contre la radicalisation vers la violence et à soutenir les initiatives visant à assurer la sécurité des Canadiens. Le 16 novembre, le ministre de la Sécurité publique, l'honorable Marco Mendicino, a invité les organisations intéressées à présenter une demande de financement dans le cadre du Fonds de résilience communautaire (FRC). À partir de 2022-23, un financement d'environ 6,5 millions de dollars sera...</p>\n","protected":false},"author":0,"featured_media":1912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,122,119,120,115,1],"tags":[],"class_list":["post-2018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement","category-dawson-research-news","category-funding-agency-news","category-funding-opportunity","category-research-news","category-uncategorized"],"_links":{"self":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/types/post"}],"replies":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/comments?post=2018"}],"version-history":[{"count":1,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2018/revisions"}],"predecessor-version":[{"id":2019,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/posts/2018/revisions/2019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media/1912"}],"wp:attachment":[{"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/media?parent=2018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/categories?post=2018"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.dawsoncollege.qc.ca/research/wp-json/wp/v2/tags?post=2018"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}