{"id":30,"date":"2014-05-27T19:07:49","date_gmt":"2014-05-27T19:07:49","guid":{"rendered":"https://www.dawsoncollege.qc.ca/finance/?page_id=30"},"modified":"2024-09-20T15:57:29","modified_gmt":"2024-09-20T19:57:29","slug":"credit-card","status":"publish","type":"page","link":"https://www.dawsoncollege.qc.ca/finance/student-fees/credit-card/","title":{"rendered":"Credit Card"},"content":{"rendered":"<p>Les étudiantes et les étudiants actuels peuvent payer leurs frais par carte de crédit dans le portail <a href=\"https://dawsoncollege.omnivox.ca\" target=\"_blank\" rel=\"noopener noreferrer\"> MyDawson</a>. Sélectionnez « Pay Fees – Credit Card » dans la barre de navigation à gauche.</p>\n<p>Pour accéder au paiement par carte de crédit, vous aurez besoin de votre numéro d'étudiant et du mot de passe que vous avez choisi lors de la configuration de votre portail.</p>\n<p>Si vous avez oublié votre mot de passe, veuillez communiquer avec le Soutien informatique (514 931-8731, poste 4357). Si vous n'avez jamais configuré votre portail, vous aurez besoin de votre numéro d'étudiant·e et de votre code permanent, puis vous suivrez les étapes indiquées sur la page d'accueil du portail MyDawson.</p>\n","protected":false},"excerpt":{"rendered":"<p>Les étudiants actuels peuvent payer leurs frais par carte de crédit via le portail MyDawson. Sélectionnez le lien \"Pay Fees - Credit Card\" dans la barre de navigation à gauche. Pour accéder au paiement par carte de crédit, vous aurez besoin de votre numéro d'étudiant et du mot de passe que vous avez choisi lors de la configuration de votre portail. Si vous...</p>\n","protected":false},"author":0,"featured_media":0,"parent":24,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/pages/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/pages"}],"about":[{"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/types/page"}],"replies":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/comments?post=30"}],"version-history":[{"count":5,"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/pages/30/revisions"}],"predecessor-version":[{"id":926,"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/pages/30/revisions/926"}],"up":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/pages/24"}],"wp:attachment":[{"href":"https://www.dawsoncollege.qc.ca/finance/wp-json/wp/v2/media?parent=30"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}