{"id":13,"date":"2014-04-16T16:47:16","date_gmt":"2014-04-16T16:47:16","guid":{"rendered":"https://www.dawsoncollege.qc.ca/awards-scholarships/?page_id=13"},"modified":"2026-04-21T17:02:50","modified_gmt":"2026-04-21T21:02:50","slug":"medical-challengesdisabilities","status":"publish","type":"page","link":"https://www.dawsoncollege.qc.ca/awards-scholarships/external-awards/medical-challengesdisabilities/","title":{"rendered":"Medical Challenges/Disabilities"},"content":{"rendered":"<h2>Site web de la formation médicale ACLS</h2>\n<p>Pour les personnes handicapées ; possibilités générales de handicap et autres liées à des conditions spécifiques.</p>\n<p><a href=\"https://www.aclsmedicaltraining.com/financial-aid-opportunities-for-disabled-individuals/\" target=\"_blank\" rel=\"noopener noreferrer\">https://www.aclsmedicaltraining.com/financial-aid-opportunities-for-disabled-individuals/</a></p>\n<hr>\n<h2>Programme de bourses de l'Alliance pour l'égalité des Canadiens aveugles</h2>\n<p>L'Alliance pour l'égalité des Canadiens aveugles (AEBC) est une organisation communautaire qui œuvre à l'amélioration de la vie des Canadiens aveugles, sourds-aveugles et malvoyants par le biais de l'éducation, de l'autonomisation et de la défense de leurs droits. Chaque année, elle offre des bourses d'études afin de récompenser des étudiants de l'enseignement supérieur aveugles, sourds-aveugles et malvoyants qui se distinguent par leurs résultats.</p>\n<p><a href=\"http://www.blindcanadians.ca/programs/scholarship\" target=\"_blank\" rel=\"noopener noreferrer\" name=\"Link\">http://www.blindcanadians.ca/programs/scholarship</a></p>\n<hr>\n<h2>Programme de bourses de l'AQEIPS</h2>\n<p>L'Association québécoise pour l'équité et l'inclusion dans l'enseignement postsecondaire (AQEIPS) offre un programme de bourses pour les étudiants handicapés de l'enseignement postsecondaire.</p>\n<p><a href=\"https://aqeips.qc.ca/en/programs/\">https://aqeips.qc.ca/en/programs/</a></p>\n<hr>\n<h2>Programme de bourses de l'Association des malentendants canadiens</h2>\n<p>Les candidats à ce programme de bourses doivent être malentendants, devenus sourds ou sourds oralistes. Des documents d'appui sont requis. Les candidats éligibles peuvent être des étudiants postsecondaires qui suivent un programme à temps plein, qu'il s'agisse d'une première inscription ou d'une reprise d'études. Le domaine d'études n'est pas un facteur dans le processus de sélection. L'éligibilité est basée sur une évaluation globale du candidat, y compris ses résultats scolaires, sa détermination à faire face à la perte d'audition et son implication dans la communauté.</p>\n<p><a href=\"https://chha.ca/scholarships/\">https://chha.ca/scholarships/</a></p>\n<hr>\n<h2>Programme national de bourses d'études des Services auditifs canadiens</h2>\n<p>La Société canadienne de l'ouïe (SCO) est fière d'offrir des bourses d'études aux étudiants sourds et malentendants afin d'éliminer les obstacles financiers à l'éducation postsecondaire. Le programme national de bourses d'études de la SCO, lancé en 2017, est le plus grand programme de bourses d'études au Canada qui soutient exclusivement les étudiants sourds et malentendants.</p>\n<p>Les bourses peuvent être utilisées pour couvrir les frais de scolarité, de résidence et de ressources éducatives. Les étudiants qui bénéficient d'une bourse restent éligibles au même niveau de financement pendant quatre années consécutives au maximum.</p>\n<p><a href=\"https://www.chs.ca/scholarship-application\">https://www.chs.ca/scholarship-application</a></p>\n<hr>\n<h2>Bourse d'études pour les survivants du cancer de l'enfant</h2>\n<p>Pour les étudiants à temps plein de l'enseignement supérieur qui ont été traités pour un cancer pendant l'enfance (le diagnostic doit avoir été posé avant ou le jour de votre 18e anniversaire).</p>\n<p><a href=\"https://www.childhoodcancer.ca/Our-Support/Programs/Programs/scholarship\">https://www.childhoodcancer.ca/Our-Support/Programs/Programs/scholarship</a></p>\n<hr>\n<h2>Bourses INCA</h2>\n<p>Chaque année, le programme de bourses d'études de l'Institut national canadien pour les aveugles (INCA) accorde de nombreuses bourses d'études et autres prix aux personnes aveugles, sourdes et aveugles ou malvoyantes dans le cadre de leur cheminement scolaire. Qu'il s'agisse de jeunes entrant en apprentissage ou dans un métier spécialisé ou d'adultes s'inscrivant à un programme de formation continue ou de certificat - et de tous ceux qui se trouvent entre les deux - de nombreuses bourses d'études et autres récompenses sont offertes.</p>\n<p>Il ne s'agit pas seulement de notes. Les bourses sont attribuées en fonction d'un large éventail de facteurs, notamment les besoins financiers, le lieu de résidence, l'engagement communautaire, la capacité à surmonter les obstacles, les compétences en matière de leadership, les ambitions, les réalisations et les objectifs. Les étudiants qui poursuivent des études en vue de l'obtention d'un diplôme, d'un certificat de qualification professionnelle, d'un apprentissage, d'un programme de formation continue ou d'un diplôme d'études supérieures sont encouragés à poser leur candidature.</p>\n<p><a href=\"https://www.cnib.ca/en/programs-and-services/learn/scholarships-and-awards?region=qc\">https://www.cnib.ca/en/programs-and-services/learn/scholarships-and-awards?region=qc</a></p>\n<hr>\n<h2 class=\"scholarshipHeading heading-no-line ut-text-transform-none\">Bourse Evelyn Joy Abramowicz</h2>\n<p>Basée sur le mérite académique, cette bourse est attribuée à un étudiant handicapé entrant au CEGEP ou inscrit dans un programme universitaire.</p>\n<p><a href=\"https://jcfmontreal.org/grants/scholarships/cegep/evelyn-joy-abramowicz-memorial-scholarship/\">https://jcfmontreal.org/grants/scholarships/cegep/evelyn-joy-abramowicz-memorial-scholarship/</a></p>\n<hr>\n<h2>Prix NEADS pour l'équité dans l'éducation</h2>\n<p>Ces prix sont destinés aux étudiants handicapés inscrits à une charge de cours de 40 % ou plus, qui font preuve d'engagement dans leur discipline universitaire, qui ont des antécédents en matière de bénévolat et/ou d'emploi et qui démontrent qu'ils ont le potentiel pour devenir des participants exceptionnels au sein de la communauté.</p>\n<p><a href=\"http://www.neads.ca/en/about/projects/ete2/scholarship/\" target=\"_blank\" rel=\"noopener noreferrer\" name=\"Link\">www.neads.ca/en/about/projects/ete2/scholarship/</a></p>\n","protected":false},"excerpt":{"rendered":"<p>Site web de formation médicale de l'ACLS Destiné aux personnes en situation de handicap ; opportunités générales pour les personnes handicapées et autres initiatives liées à des pathologies spécifiques. https://www.aclsmedicaltraining.com/financial-aid-opportunities-for-disabled-individuals/ Programme de bourses de l'Alliance pour l'égalité des Canadiens aveugles L'Alliance pour l'égalité des Canadiens aveugles (AEBC) est une organisation de base qui œuvre à l'amélioration de la vie des Canadiens aveugles, sourds-aveugles et malvoyants par le biais de l'éducation, de l'autonomisation,…</p>\n","protected":false},"author":0,"featured_media":0,"parent":9,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/pages/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/pages"}],"about":[{"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/types/page"}],"replies":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/comments?post=13"}],"version-history":[{"count":15,"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/pages/13/revisions"}],"predecessor-version":[{"id":3451,"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/pages/13/revisions/3451"}],"up":[{"embeddable":true,"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/pages/9"}],"wp:attachment":[{"href":"https://www.dawsoncollege.qc.ca/awards-scholarships/wp-json/wp/v2/media?parent=13"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}